{"id":2762,"date":"2016-10-17T21:03:15","date_gmt":"2016-10-17T19:03:15","guid":{"rendered":"https:\/\/auftragsmalerei-kwast-berlin.de\/?page_id=2762"},"modified":"2016-10-17T21:03:15","modified_gmt":"2016-10-17T19:03:15","slug":"fassadenmalerei-dalgow","status":"publish","type":"page","link":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/fassadenmalerei-dalgow\/","title":{"rendered":"Fassadenmalerei &#8211; Dalgow"},"content":{"rendered":"<h3>Auftraggeber: privat \/ Fassadenfarben auf Putz \/ T\u00fcr- und Fenstergr\u00f6\u00dfe<\/h3>\n<p>F\u00fcr ein Einfamilienhaus wurden alle T\u00fcren und Fenster mit einem gemalten Stuck gerahmt. Freu mich da wirklich auf Folgeauftr\u00e4ge.<\/p>\n<div class=\"content_block\" id=\"custom_post_widget-2758\"><p><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2759\" src=\"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/wp-content\/uploads\/fassadenmalerei-dalgow-gr.1.jpg\" alt=\"kwast-fassadenmalerei-dalgow-gr-1\" width=\"900\" height=\"675\" \/> <img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-2760\" src=\"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/wp-content\/uploads\/fassadenmalerei-dalgow-gr.2.jpg\" alt=\"kwast-fassadenmalerei-dalgow-gr-2\" width=\"900\" height=\"1170\" \/><\/p>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Auftraggeber: privat \/ Fassadenfarben auf Putz \/ T\u00fcr- und Fenstergr\u00f6\u00dfe F\u00fcr ein Einfamilienhaus wurden alle T\u00fcren und Fenster mit einem gemalten Stuck gerahmt. Freu mich da wirklich auf Folgeauftr\u00e4ge.<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":137,"menu_order":20,"comment_status":"closed","ping_status":"closed","template":"detailseiten.php","meta":{"footnotes":""},"class_list":["post-2762","page","type-page","status-publish","hentry","brick"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fassadenmalerei - Dalgow - Commissioned Painting Kwast Berlin<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/fassadenmalerei-dalgow\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fassadenmalerei - Dalgow - Commissioned Painting Kwast Berlin\" \/>\n<meta property=\"og:description\" content=\"Auftraggeber: privat \/ Fassadenfarben auf Putz \/ T\u00fcr- und Fenstergr\u00f6\u00dfe F\u00fcr ein Einfamilienhaus wurden alle T\u00fcren und Fenster mit einem gemalten Stuck gerahmt. Freu mich da wirklich auf Folgeauftr\u00e4ge.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/fassadenmalerei-dalgow\/\" \/>\n<meta property=\"og:site_name\" content=\"Commissioned Painting Kwast Berlin\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/facade-painting\\\/fassadenmalerei-dalgow\\\/\",\"url\":\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/facade-painting\\\/fassadenmalerei-dalgow\\\/\",\"name\":\"Fassadenmalerei - Dalgow - Commissioned Painting Kwast Berlin\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/#website\"},\"datePublished\":\"2016-10-17T19:03:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/facade-painting\\\/fassadenmalerei-dalgow\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/facade-painting\\\/fassadenmalerei-dalgow\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/facade-painting\\\/fassadenmalerei-dalgow\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Facade painting\",\"item\":\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/facade-painting\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Fassadenmalerei &#8211; Dalgow\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/\",\"name\":\"Commissioned Painting Kwast Berlin\",\"description\":\"Commissioned painting for theatre and film, fairs and museums, wall, facade and portrait\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/auftragsmalerei-kwast-berlin.de\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fassadenmalerei - Dalgow - Commissioned Painting Kwast Berlin","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/fassadenmalerei-dalgow\/","og_locale":"en_US","og_type":"article","og_title":"Fassadenmalerei - Dalgow - Commissioned Painting Kwast Berlin","og_description":"Auftraggeber: privat \/ Fassadenfarben auf Putz \/ T\u00fcr- und Fenstergr\u00f6\u00dfe F\u00fcr ein Einfamilienhaus wurden alle T\u00fcren und Fenster mit einem gemalten Stuck gerahmt. Freu mich da wirklich auf Folgeauftr\u00e4ge.","og_url":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/fassadenmalerei-dalgow\/","og_site_name":"Commissioned Painting Kwast Berlin","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/fassadenmalerei-dalgow\/","url":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/fassadenmalerei-dalgow\/","name":"Fassadenmalerei - Dalgow - Commissioned Painting Kwast Berlin","isPartOf":{"@id":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/#website"},"datePublished":"2016-10-17T19:03:15+00:00","breadcrumb":{"@id":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/fassadenmalerei-dalgow\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/fassadenmalerei-dalgow\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/fassadenmalerei-dalgow\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/"},{"@type":"ListItem","position":2,"name":"Facade painting","item":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/facade-painting\/"},{"@type":"ListItem","position":3,"name":"Fassadenmalerei &#8211; Dalgow"}]},{"@type":"WebSite","@id":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/#website","url":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/","name":"Commissioned Painting Kwast Berlin","description":"Commissioned painting for theatre and film, fairs and museums, wall, facade and portrait","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/wp-json\/wp\/v2\/pages\/2762","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/wp-json\/wp\/v2\/comments?post=2762"}],"version-history":[{"count":0,"href":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/wp-json\/wp\/v2\/pages\/2762\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/wp-json\/wp\/v2\/pages\/137"}],"wp:attachment":[{"href":"https:\/\/auftragsmalerei-kwast-berlin.de\/en\/wp-json\/wp\/v2\/media?parent=2762"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}